{"id":6339,"date":"2022-11-29T11:58:51","date_gmt":"2022-11-29T10:58:51","guid":{"rendered":"https:\/\/www.unirsm.sm\/centro-studi-sulla-memoria\/?post_type=publications&#038;p=6339"},"modified":"2025-02-19T15:18:05","modified_gmt":"2025-02-19T14:18:05","slug":"giocare-alla-memoria","status":"publish","type":"publications","link":"https:\/\/www.unirsm.sm\/centro-studi-sulla-memoria\/pubblicazione\/giocare-alla-memoria\/","title":{"rendered":"Giocare alla memoria"},"author":4,"template":"","meta":{"_acf_changed":false},"class_list":["post-6339","publications","type-publications","status-publish","hentry","publications_types-libro","publications_roles-autore"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Giocare alla memoria | Centro Studi sulla Memoria<\/title>\n<meta name=\"description\" content=\"Le pubblicazioni del Centro Studi sulla Memoria! Leggi Giocare alla memoria\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.unirsm.sm\/centro-studi-sulla-memoria\/pubblicazione\/giocare-alla-memoria\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Giocare alla memoria | Centro Studi sulla Memoria\" \/>\n<meta property=\"og:description\" content=\"Le pubblicazioni del Centro Studi sulla Memoria! Leggi Giocare alla memoria\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.unirsm.sm\/centro-studi-sulla-memoria\/pubblicazione\/giocare-alla-memoria\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro Studi sulla Memoria\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-19T14:18:05+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.unirsm.sm\\\/centro-studi-sulla-memoria\\\/pubblicazione\\\/giocare-alla-memoria\\\/\",\"url\":\"https:\\\/\\\/www.unirsm.sm\\\/centro-studi-sulla-memoria\\\/pubblicazione\\\/giocare-alla-memoria\\\/\",\"name\":\"Giocare alla memoria | Centro Studi sulla Memoria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unirsm.sm\\\/centro-studi-sulla-memoria\\\/#website\"},\"datePublished\":\"2022-11-29T10:58:51+00:00\",\"dateModified\":\"2025-02-19T14:18:05+00:00\",\"description\":\"Le pubblicazioni del Centro Studi sulla Memoria! Leggi Giocare alla memoria\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.unirsm.sm\\\/centro-studi-sulla-memoria\\\/pubblicazione\\\/giocare-alla-memoria\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.unirsm.sm\\\/centro-studi-sulla-memoria\\\/pubblicazione\\\/giocare-alla-memoria\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.unirsm.sm\\\/centro-studi-sulla-memoria\\\/pubblicazione\\\/giocare-alla-memoria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.unirsm.sm\\\/centro-studi-sulla-memoria\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Giocare alla memoria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.unirsm.sm\\\/centro-studi-sulla-memoria\\\/#website\",\"url\":\"https:\\\/\\\/www.unirsm.sm\\\/centro-studi-sulla-memoria\\\/\",\"name\":\"Centro Studi sulla Memoria\",\"description\":\"Ecco un altro sito UNIRSM network\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.unirsm.sm\\\/centro-studi-sulla-memoria\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Giocare alla memoria | Centro Studi sulla Memoria","description":"Le pubblicazioni del Centro Studi sulla Memoria! Leggi Giocare alla memoria","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.unirsm.sm\/centro-studi-sulla-memoria\/pubblicazione\/giocare-alla-memoria\/","og_locale":"it_IT","og_type":"article","og_title":"Giocare alla memoria | Centro Studi sulla Memoria","og_description":"Le pubblicazioni del Centro Studi sulla Memoria! Leggi Giocare alla memoria","og_url":"https:\/\/www.unirsm.sm\/centro-studi-sulla-memoria\/pubblicazione\/giocare-alla-memoria\/","og_site_name":"Centro Studi sulla Memoria","article_modified_time":"2025-02-19T14:18:05+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.unirsm.sm\/centro-studi-sulla-memoria\/pubblicazione\/giocare-alla-memoria\/","url":"https:\/\/www.unirsm.sm\/centro-studi-sulla-memoria\/pubblicazione\/giocare-alla-memoria\/","name":"Giocare alla memoria | Centro Studi sulla Memoria","isPartOf":{"@id":"https:\/\/www.unirsm.sm\/centro-studi-sulla-memoria\/#website"},"datePublished":"2022-11-29T10:58:51+00:00","dateModified":"2025-02-19T14:18:05+00:00","description":"Le pubblicazioni del Centro Studi sulla Memoria! Leggi Giocare alla memoria","breadcrumb":{"@id":"https:\/\/www.unirsm.sm\/centro-studi-sulla-memoria\/pubblicazione\/giocare-alla-memoria\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.unirsm.sm\/centro-studi-sulla-memoria\/pubblicazione\/giocare-alla-memoria\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.unirsm.sm\/centro-studi-sulla-memoria\/pubblicazione\/giocare-alla-memoria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.unirsm.sm\/centro-studi-sulla-memoria\/"},{"@type":"ListItem","position":2,"name":"Giocare alla memoria"}]},{"@type":"WebSite","@id":"https:\/\/www.unirsm.sm\/centro-studi-sulla-memoria\/#website","url":"https:\/\/www.unirsm.sm\/centro-studi-sulla-memoria\/","name":"Centro Studi sulla Memoria","description":"Ecco un altro sito UNIRSM network","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.unirsm.sm\/centro-studi-sulla-memoria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.unirsm.sm\/centro-studi-sulla-memoria\/wp-json\/wp\/v2\/publications\/6339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unirsm.sm\/centro-studi-sulla-memoria\/wp-json\/wp\/v2\/publications"}],"about":[{"href":"https:\/\/www.unirsm.sm\/centro-studi-sulla-memoria\/wp-json\/wp\/v2\/types\/publications"}],"author":[{"embeddable":true,"href":"https:\/\/www.unirsm.sm\/centro-studi-sulla-memoria\/wp-json\/wp\/v2\/users\/4"}],"wp:attachment":[{"href":"https:\/\/www.unirsm.sm\/centro-studi-sulla-memoria\/wp-json\/wp\/v2\/media?parent=6339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}