{"id":5067,"date":"2022-12-12T10:59:35","date_gmt":"2022-12-12T09:59:35","guid":{"rendered":"https:\/\/www.unirsm.sm\/ingegneria-gestionale\/?page_id=5067"},"modified":"2026-04-10T14:38:31","modified_gmt":"2026-04-10T12:38:31","slug":"orario-delle-lezioni","status":"publish","type":"page","link":"https:\/\/www.unirsm.sm\/ingegneria-gestionale\/orario-delle-lezioni\/","title":{"rendered":"Orario delle lezioni"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-5067","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Orario delle lezioni | Ingegneria Gestionale<\/title>\n<meta name=\"description\" content=\"Orario delle lezioni di Ingegneria Gestionale. Ti diamo il benvenuto a UNIRSM!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.unirsm.sm\/ingegneria-gestionale\/orario-delle-lezioni\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Orario delle lezioni | Ingegneria Gestionale\" \/>\n<meta property=\"og:description\" content=\"Orario delle lezioni di Ingegneria Gestionale. Ti diamo il benvenuto a UNIRSM!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.unirsm.sm\/ingegneria-gestionale\/orario-delle-lezioni\/\" \/>\n<meta property=\"og:site_name\" content=\"Ingegneria Gestionale\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-10T12:38:31+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.unirsm.sm\\\/ingegneria-gestionale\\\/orario-delle-lezioni\\\/\",\"url\":\"https:\\\/\\\/www.unirsm.sm\\\/ingegneria-gestionale\\\/orario-delle-lezioni\\\/\",\"name\":\"Orario delle lezioni | Ingegneria Gestionale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unirsm.sm\\\/ingegneria-gestionale\\\/#website\"},\"datePublished\":\"2022-12-12T09:59:35+00:00\",\"dateModified\":\"2026-04-10T12:38:31+00:00\",\"description\":\"Orario delle lezioni di Ingegneria Gestionale. Ti diamo il benvenuto a UNIRSM!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.unirsm.sm\\\/ingegneria-gestionale\\\/orario-delle-lezioni\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.unirsm.sm\\\/ingegneria-gestionale\\\/orario-delle-lezioni\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.unirsm.sm\\\/ingegneria-gestionale\\\/orario-delle-lezioni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.unirsm.sm\\\/ingegneria-gestionale\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Orario delle lezioni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.unirsm.sm\\\/ingegneria-gestionale\\\/#website\",\"url\":\"https:\\\/\\\/www.unirsm.sm\\\/ingegneria-gestionale\\\/\",\"name\":\"Ingegneria Gestionale\",\"description\":\"Corso di laurea in Ingegneria Gestionale\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.unirsm.sm\\\/ingegneria-gestionale\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Orario delle lezioni | Ingegneria Gestionale","description":"Orario delle lezioni di Ingegneria Gestionale. Ti diamo il benvenuto a UNIRSM!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.unirsm.sm\/ingegneria-gestionale\/orario-delle-lezioni\/","og_locale":"it_IT","og_type":"article","og_title":"Orario delle lezioni | Ingegneria Gestionale","og_description":"Orario delle lezioni di Ingegneria Gestionale. Ti diamo il benvenuto a UNIRSM!","og_url":"https:\/\/www.unirsm.sm\/ingegneria-gestionale\/orario-delle-lezioni\/","og_site_name":"Ingegneria Gestionale","article_modified_time":"2026-04-10T12:38:31+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.unirsm.sm\/ingegneria-gestionale\/orario-delle-lezioni\/","url":"https:\/\/www.unirsm.sm\/ingegneria-gestionale\/orario-delle-lezioni\/","name":"Orario delle lezioni | Ingegneria Gestionale","isPartOf":{"@id":"https:\/\/www.unirsm.sm\/ingegneria-gestionale\/#website"},"datePublished":"2022-12-12T09:59:35+00:00","dateModified":"2026-04-10T12:38:31+00:00","description":"Orario delle lezioni di Ingegneria Gestionale. Ti diamo il benvenuto a UNIRSM!","breadcrumb":{"@id":"https:\/\/www.unirsm.sm\/ingegneria-gestionale\/orario-delle-lezioni\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.unirsm.sm\/ingegneria-gestionale\/orario-delle-lezioni\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.unirsm.sm\/ingegneria-gestionale\/orario-delle-lezioni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.unirsm.sm\/ingegneria-gestionale\/"},{"@type":"ListItem","position":2,"name":"Orario delle lezioni"}]},{"@type":"WebSite","@id":"https:\/\/www.unirsm.sm\/ingegneria-gestionale\/#website","url":"https:\/\/www.unirsm.sm\/ingegneria-gestionale\/","name":"Ingegneria Gestionale","description":"Corso di laurea in Ingegneria Gestionale","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.unirsm.sm\/ingegneria-gestionale\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.unirsm.sm\/ingegneria-gestionale\/wp-json\/wp\/v2\/pages\/5067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unirsm.sm\/ingegneria-gestionale\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.unirsm.sm\/ingegneria-gestionale\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.unirsm.sm\/ingegneria-gestionale\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unirsm.sm\/ingegneria-gestionale\/wp-json\/wp\/v2\/comments?post=5067"}],"version-history":[{"count":36,"href":"https:\/\/www.unirsm.sm\/ingegneria-gestionale\/wp-json\/wp\/v2\/pages\/5067\/revisions"}],"predecessor-version":[{"id":9572,"href":"https:\/\/www.unirsm.sm\/ingegneria-gestionale\/wp-json\/wp\/v2\/pages\/5067\/revisions\/9572"}],"wp:attachment":[{"href":"https:\/\/www.unirsm.sm\/ingegneria-gestionale\/wp-json\/wp\/v2\/media?parent=5067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}